{"id":31003,"date":"2025-05-22T11:09:48","date_gmt":"2025-05-22T11:09:48","guid":{"rendered":"https:\/\/mon-agent-ia.fr\/blog\/?p=31003"},"modified":"2025-05-22T11:09:50","modified_gmt":"2025-05-22T11:09:50","slug":"gpt-seguro-la-transicion-de-veolia-de-la-ia-generativa-a-la-ia-agente","status":"publish","type":"post","link":"https:\/\/mon-agent-ia.fr\/blog\/es-mx\/gpt-seguro-la-transicion-de-veolia-de-la-ia-generativa-a-la-ia-agente\/","title":{"rendered":"GPT seguro: la transici\u00f3n de Veolia de la IA generativa a la IA agente"},"content":{"rendered":"<p class=\"wp-block-paragraph\">En un mundo donde la transformaci\u00f3n digital se ha vuelto inevitable, Veolia se destaca por su enfoque audaz hacia la IA generativa y agente. Desde su lanzamiento en septiembre de 2023, la aplicaci\u00f3n Secure GPT ha ilustrado perfectamente esta transici\u00f3n, simbolizando no solo la innovaci\u00f3n tecnol\u00f3gica sino tambi\u00e9n un fuerte compromiso con un futuro sostenible. En este art\u00edculo exploraremos las etapas clave de esta transformaci\u00f3n, los desaf\u00edos encontrados y c\u00f3mo la integraci\u00f3n de soluciones inteligentes se ha vuelto esencial para la econom\u00eda circular.<\/p>\n\n<h2 class=\"wp-block-heading\">El nacimiento de Secure GPT: de la IA generativa a la IA agente<\/h2>\n\n<p class=\"wp-block-paragraph\">El viaje de Veolia hacia una IA agente realmente despeg\u00f3 con el lanzamiento de Secure GPT, dise\u00f1ado para reunir un ecosistema de agentes y asistentes inteligentes para atender a los empleados. A enero de 2025, este sistema ya cuenta con m\u00e1s de 214 asistentes de IA, utilizados diariamente por 58.000 empleados en 41 entidades. Esta impresionante cifra demuestra el compromiso del grupo de aprovechar las nuevas tecnolog\u00edas para mejorar sus operaciones internas.<\/p>\n\n<h3 class=\"wp-block-heading\">Una visi\u00f3n centrada en la transformaci\u00f3n digital<\/h3>\n\n<p class=\"wp-block-paragraph\">La transici\u00f3n de Veolia a una infraestructura impulsada por IA es parte de una transformaci\u00f3n digital m\u00e1s amplia que comenz\u00f3 en 2013. La empresa, que ahora tiene m\u00e1s de 218.000 empleados, lider\u00f3 el camino con la adopci\u00f3n de Google Workspace, seguido de integraciones clave con Google Cloud y AWS. A lo largo de los a\u00f1os, Veolia ha implementado una estrategia \u201ccloud first\u201d, favoreciendo los servicios en l\u00ednea para mejorar su eficiencia operativa.<\/p>\n\n<p class=\"wp-block-paragraph\">Esta estrategia ha fomentado el surgimiento de la IA generativa, encarnada por ChatGPT, que ha permitido a la empresa aprovechar las oportunidades de innovaci\u00f3n al mismo tiempo que es consciente de los desaf\u00edos, como los riesgos de seguridad y sesgo. Esta din\u00e1mica ha reforzado la idea de que la IA es una herramienta poderosa, capaz de optimizar procesos respetando los valores de sostenibilidad.<\/p>\n\n<h3 class=\"wp-block-heading\">Una infraestructura s\u00f3lida: la arquitectura Secure GPT<\/h3>\n\n<p class=\"wp-block-paragraph\">Desde el principio, la arquitectura Secure GPT fue dise\u00f1ada \u201c <strong>a prop\u00f3sito<\/strong> \u00bb integrar diferentes modelos de lenguaje. Ya sea para responder preguntas espec\u00edficas o traducir documentos, cada asistente es configurable seg\u00fan las necesidades del usuario. De esta forma, se encuentran disponibles m\u00e1s de doce LLM (Large Language Model), cada uno seleccionado por su capacidad para abordar variados casos de uso.<\/p>\n\n<ul class=\"wp-block-list\"><li>LLM para conversaci\u00f3n<\/li><li>LLM de Traducci\u00f3n<\/li><li>LLM para consultar archivos PDF<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">Durante la fase de implementaci\u00f3n generalizada en octubre de 2023, se implement\u00f3 una API bien estructurada para garantizar el acceso de los equipos de TI en 57 pa\u00edses. Esta capacidad de implementar herramientas r\u00e1pidamente agiliz\u00f3 el proceso e impuls\u00f3 la eficiencia de la organizaci\u00f3n a nuevas alturas.<\/p>\n\n<h3 class=\"wp-block-heading\">Un enfoque en la sostenibilidad y la innovaci\u00f3n<\/h3>\n\n<p class=\"wp-block-paragraph\">La transici\u00f3n a una IA agente no se trata solo de optimizar los procesos internos; Tambi\u00e9n es parte de una visi\u00f3n m\u00e1s amplia de la sostenibilidad. Veolia participa activamente en su enfoque hacia <strong>sostenibilidad<\/strong> destacando el uso de modelos de IA que consumen menos energ\u00eda como parte de su programa AI for Green Up. Esta iniciativa tiene como objetivo minimizar los costos ambientales inherentes al uso de la inteligencia artificial y maximizar los beneficios. <\/p>\n\n<p class=\"wp-block-paragraph\">Fouad Maach, responsable de arquitectura e ingenier\u00eda de TI, destaca que el objetivo es<strong>aumentar<\/strong> las capacidades de los empleados en lugar de sustituirlos, lo que ilustra un claro compromiso con el respeto al medio ambiente y la promoci\u00f3n de la innovaci\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\">La evoluci\u00f3n de los sistemas de asistencia en Veolia<\/h2>\n\n<p class=\"wp-block-paragraph\">En enero de 2025, Veolia registr\u00f3 un fuerte uso de sus soluciones de asistencia, lo que demuestra la curva de crecimiento exponencial de la integraci\u00f3n de tecnolog\u00edas inteligentes. \u00bfPero c\u00f3mo se ha traducido esta evoluci\u00f3n concretamente en la vida cotidiana de los equipos?<\/p>\n\n<h3 class=\"wp-block-heading\">Asistentes de IA: una respuesta a necesidades variadas<\/h3>\n\n<p class=\"wp-block-paragraph\">Los diversos asistentes de IA desarrollados dentro de Secure GPT se pueden clasificar en tres niveles de complejidad. Esta clasificaci\u00f3n nos permite comprender mejor su capacidad y alcance:<\/p>\n\n<figure class=\"wp-block-table\"><table>\n<thead>\n<tr>\n<th>Nivel<\/th>\n<th>Descripci\u00f3n<\/th>\n<th>Ejemplos de uso<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Nivel 1<\/td>\n<td>LLM con orientaci\u00f3n personalizada para abordar un caso espec\u00edfico<\/td>\n<td>Soporte b\u00e1sico al usuario<\/td>\n<\/tr>\n<tr>\n<td>Nivel 2<\/td>\n<td>Uso de RAG (Recuperaci\u00f3n-Generaci\u00f3n Aumentada)<\/td>\n<td>Consulta de documentos complejos<\/td>\n<\/tr>\n<tr>\n<td>Nivel 3<\/td>\n<td>Capacidad para procesar datos estructurados y no estructurados<\/td>\n<td>Interacciones con el sistema de informaci\u00f3n de la empresa<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/figure>\n\n<p class=\"wp-block-paragraph\">Un asistente de nivel 3 podr\u00eda, por ejemplo, interactuar con el sistema de informaci\u00f3n de la empresa para enviar \u00f3rdenes de compra o enviar correos electr\u00f3nicos. Estas herramientas son esenciales en la infraestructura de Veolia, facilitando el intercambio de informaci\u00f3n y la toma de decisiones estrat\u00e9gicas.<\/p>\n\n<h3 class=\"wp-block-heading\">La importancia de la cultura y la formaci\u00f3n<\/h3>\n\n<p class=\"wp-block-paragraph\">Otro aspecto fundamental de la implementaci\u00f3n de Secure GPT es la <strong>formaci\u00f3n de empleados<\/strong>. Entre septiembre y noviembre de 2023, se implement\u00f3 un programa de aculturaci\u00f3n, destinado a educar a los empleados sobre las capacidades de la IA generativa y agente. Se form\u00f3 un equipo de 400 campeones de IA para capacitar a m\u00e1s de 13.000 empleados en el uso de estas nuevas herramientas, lo que de hecho facilit\u00f3 la aceptaci\u00f3n e integraci\u00f3n de estas soluciones inteligentes.<\/p>\n\n<p class=\"wp-block-paragraph\">La capacitaci\u00f3n no se trata solo de ense\u00f1ar los conceptos b\u00e1sicos de la IA, sino tambi\u00e9n de revisar los procesos operativos. Esto permite que los equipos de \u201cdatos y digitales\u201d construyan conjuntamente soluciones alineadas con los objetivos de<strong>econom\u00eda circular<\/strong> del grupo, ya sea reduciendo residuos o mejorando el rendimiento energ\u00e9tico.<\/p>\n\n<h3 class=\"wp-block-heading\">Una tendencia creciente hacia la IA agente<\/h3>\n\n<p class=\"wp-block-paragraph\">El auge de la IA agente en Veolia ofrece una visi\u00f3n fascinante del futuro de la inteligencia dentro de las grandes organizaciones. A partir de junio de 2024 se han iniciado experimentos para crear un <strong>plataforma agente<\/strong> que conecta m\u00faltiples asistentes y agentes, cada uno con roles espec\u00edficos. Estos agentes pueden interactuar, intercambiar informaci\u00f3n e integrarse perfectamente con los sistemas de TI existentes. Este modelo de flujo multiagente deber\u00eda revolucionar los m\u00e9todos de trabajo dentro de la empresa.<\/p>\n\n<h2 class=\"wp-block-heading\">Retos por superar y \u00e9xitos por celebrar<\/h2>\n\n<p class=\"wp-block-paragraph\">Toda transformaci\u00f3n, incluso una prometedora, presenta sus desaf\u00edos. Para Veolia, la gesti\u00f3n de los riesgos asociados a la IA generativa sigue siendo una prioridad, en particular en lo que respecta a la seguridad de los datos y la protecci\u00f3n contra sesgos. A medida que avanzan las tecnolog\u00edas, la empresa contin\u00faa evaluando las mejores pr\u00e1cticas para minimizar estos riesgos y aprovechar al m\u00e1ximo las capacidades de IA.<\/p>\n\n<h3 class=\"wp-block-heading\">Identificar y minimizar riesgos<\/h3>\n\n<p class=\"wp-block-paragraph\">Fouad Maach plante\u00f3 importantes preocupaciones como la exfiltraci\u00f3n de datos, la violaci\u00f3n de la propiedad intelectual y las alucinaciones de modelos de inteligencia artificial. Analizar estas cuestiones es fundamental para garantizar no s\u00f3lo la protecci\u00f3n de la empresa, sino tambi\u00e9n la confianza de los usuarios en estas tecnolog\u00edas. Por ello, Veolia est\u00e1 trabajando para desarrollar estrategias de mitigaci\u00f3n s\u00f3lidas, garantizando que la IA generativa y agente sea compatible con sus valores de sostenibilidad y \u00e9tica.<\/p>\n\n<h3 class=\"wp-block-heading\">Construyendo desempe\u00f1o a trav\u00e9s de la innovaci\u00f3n<\/h3>\n\n<p class=\"wp-block-paragraph\">Al emprender este camino, Veolia no se limita a adoptar tecnolog\u00edas: tambi\u00e9n crea una cultura de innovaci\u00f3n impregnada de responsabilidad. Al integrar IA generativa y agente, la empresa garantiza mantenerse a la vanguardia, no solo para sus equipos, sino tambi\u00e9n para sus clientes y el medio ambiente. Todo este proceso sentar\u00eda las bases para una red de apoyo inteligente, garantizando soluciones efectivas a desaf\u00edos complejos relacionados con los recursos naturales y la gesti\u00f3n de residuos.<\/p>\n\n<h3 class=\"wp-block-heading\">Una visi\u00f3n del futuro impulsada por la innovaci\u00f3n y la colaboraci\u00f3n<\/h3>\n\n<p class=\"wp-block-paragraph\">Veolia encarna una visi\u00f3n de futuro donde la innovaci\u00f3n tecnol\u00f3gica y la sostenibilidad no son elementos opuestos, sino complementarios. A trav\u00e9s de su plataforma Secure GPT y su enfoque activo hacia la energ\u00eda y el medio ambiente, la empresa est\u00e1 trabajando hacia un mundo donde la IA generativa y agente transforma la explotaci\u00f3n de recursos en un modelo de econom\u00eda circular.<\/p>\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, a medida que las soluciones tecnol\u00f3gicas contin\u00faan evolucionando, la clave del \u00e9xito radica en un enfoque proactivo, que combine capacitaci\u00f3n, colaboraci\u00f3n y evaluaci\u00f3n constante de los resultados. Al mantener este equilibrio entre avanzar tecnol\u00f3gicamente y permanecer anclado en los valores fundamentales de la sostenibilidad y la \u00e9tica, Veolia est\u00e1 en una posici\u00f3n ideal para afrontar los futuros desaf\u00edos medioambientales y de desarrollo sostenible.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>En un mundo donde la transformaci\u00f3n digital se ha vuelto inevitable, Veolia se destaca por su enfoque audaz hacia la IA generativa y agente. Desde su lanzamiento en septiembre de 2023, la aplicaci\u00f3n Secure GPT ha ilustrado perfectamente esta transici\u00f3n, simbolizando no solo la innovaci\u00f3n tecnol\u00f3gica sino tambi\u00e9n un fuerte compromiso con un futuro sostenible. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-31003","post","type-post","status-publish","format-standard","hentry","category-non-classe-es-mx"],"_links":{"self":[{"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/posts\/31003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/comments?post=31003"}],"version-history":[{"count":1,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/posts\/31003\/revisions"}],"predecessor-version":[{"id":31004,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/posts\/31003\/revisions\/31004"}],"wp:attachment":[{"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/media?parent=31003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/categories?post=31003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/tags?post=31003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}