{"id":34737,"date":"2025-05-31T07:09:22","date_gmt":"2025-05-31T07:09:22","guid":{"rendered":"https:\/\/mon-agent-ia.fr\/blog\/?p=34737"},"modified":"2025-05-31T07:09:24","modified_gmt":"2025-05-31T07:09:24","slug":"joule-e-agentes-inteligentes-a-sap-revela-seus-planos-e-aspiracoes-para-o-futuro","status":"publish","type":"post","link":"https:\/\/mon-agent-ia.fr\/blog\/pt\/joule-e-agentes-inteligentes-a-sap-revela-seus-planos-e-aspiracoes-para-o-futuro\/","title":{"rendered":"Joule e agentes inteligentes: a SAP revela seus planos e aspira\u00e7\u00f5es para o futuro"},"content":{"rendered":"<p class=\"wp-block-paragraph\">No alvorecer da revolu\u00e7\u00e3o digital, \u00e0 medida que a tecnologia evolui a um ritmo fren\u00e9tico, <strong>SEIVA<\/strong>, l\u00edder na \u00e1rea de <strong>software empresarial<\/strong>, est\u00e1 preparando uma grande transforma\u00e7\u00e3o em seu conjunto de ferramentas. Nos eventos Sapphire 2025, a empresa revelou suas ambi\u00e7\u00f5es em intelig\u00eancia artificial com a apresenta\u00e7\u00e3o de seu assistente <strong>Joule<\/strong> e seu <strong>agentes inteligentes<\/strong>. Apesar da ado\u00e7\u00e3o ainda hesitante por parte de alguns clientes, a SAP est\u00e1 planejando com anteced\u00eancia um roteiro ambicioso, com foco em<strong>inova\u00e7\u00e3o<\/strong> para se tornar o cora\u00e7\u00e3o das atividades digitais e<strong>automa\u00e7\u00e3o<\/strong> de seus usu\u00e1rios.<\/p>\n\n<p class=\"wp-block-paragraph\">Este foco no<strong>intelig\u00eancia artificial<\/strong> e agentes inteligentes visam n\u00e3o apenas otimizar a gest\u00e3o dos processos de neg\u00f3cio, mas tamb\u00e9m oferecer solu\u00e7\u00f5es mais personalizadas e adaptadas aos crescentes desafios do mundo profissional moderno.<\/p>\n\n<h2 class=\"wp-block-heading\">Ambi\u00e7\u00f5es da SAP: Joule, um assistente inteligente ao servi\u00e7o das empresas<\/h2>\n\n<p class=\"wp-block-paragraph\">Nas recentes edi\u00e7\u00f5es norte-americana e europeia da Sapphire, a SAP destacou <strong>Joule<\/strong>, seu assistente inteligente, que pode redefinir a maneira como as empresas interagem com seus sistemas. Com um total impressionante de 34.000 clientes usando o pacote <strong>IA empresarial<\/strong>, fica claro que a transforma\u00e7\u00e3o digital est\u00e1 no centro das preocupa\u00e7\u00f5es da SAP.<\/p>\n\n<h3 class=\"wp-block-heading\">Integra\u00e7\u00e3o do Joule com o Microsoft Copilot<\/h3>\n\n<p class=\"wp-block-paragraph\">Um dos destaques da edi\u00e7\u00e3o de 2025 \u00e9 a expectativa em torno da integra\u00e7\u00e3o da Joule com <strong>Copiloto da Microsoft<\/strong>. O objetivo \u00e9 estabelecer uma conex\u00e3o bidirecional entre os dois sistemas. A previs\u00e3o \u00e9 que esse recurso esteja dispon\u00edvel no segundo trimestre de 2025, e essa sinergia promete expandir significativamente as capacidades de automa\u00e7\u00e3o dos usu\u00e1rios.<\/p>\n\n<p class=\"wp-block-paragraph\">O Joule estar\u00e1 ent\u00e3o acess\u00edvel por meio de uma barra de a\u00e7\u00e3o, melhorando a interface do usu\u00e1rio com uma experi\u00eancia mais fluida e interativa. Esta mudan\u00e7a \u00e9 resultado da aquisi\u00e7\u00e3o de <strong>WalkMe<\/strong>, que enriquece o SAP GUI ao explicar visualmente os v\u00e1rios componentes da interface.<\/p>\n\n<h3 class=\"wp-block-heading\">Um conjunto de habilidades na ponta dos seus dedos<\/h3>\n\n<p class=\"wp-block-paragraph\">Atualmente, o Joule tem capacidade para operar at\u00e9 1600 <strong>a\u00e7\u00f5es<\/strong>, representando aproximadamente 80% dos fluxos de trabalho mais frequentemente utilizados nos sistemas <strong>SEIVA<\/strong>. Essas habilidades abrangem diversas \u00e1reas, como finan\u00e7as, gest\u00e3o da cadeia de suprimentos e recursos humanos, e permitem o monitoramento, a modifica\u00e7\u00e3o e a an\u00e1lise de dados de forma integrada.<\/p>\n\n<ul class=\"wp-block-list\"><li>Gest\u00e3o financeira<\/li><li>Otimiza\u00e7\u00e3o da cadeia de suprimentos<\/li><li>Suporte de RH<\/li><li>Manuseio de documentos e entrada de dados<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">O acesso a essas habilidades varia dependendo das solu\u00e7\u00f5es escolhidas pelos clientes como parte de sua parceria com a SAP.<\/p>\n\n<h3 class=\"wp-block-heading\">Solu\u00e7\u00f5es futuras: um roteiro movimentado para 2025<\/h3>\n\n<p class=\"wp-block-paragraph\">Os pr\u00f3ximos passos incluem solu\u00e7\u00f5es integradas para diversas ferramentas SAP, como Ariba Procurement, Fieldglass e outras, planejadas para o terceiro trimestre de 2025. Esses desenvolvimentos tamb\u00e9m ser\u00e3o acompanhados por solu\u00e7\u00f5es espec\u00edficas nas \u00e1reas de Field Service Management e Integrated Business Planning.<\/p>\n\n<p class=\"wp-block-paragraph\">Nessa din\u00e2mica, a SAP tamb\u00e9m promete aos seus clientes a possibilidade de desenvolver <strong>habilidades<\/strong> personalizado via Joule Studio, o que os tornar\u00e1 respons\u00e1veis \u200b\u200bpor enriquecer seus pr\u00f3prios processos de neg\u00f3cios.<\/p>\n\n<figure class=\"wp-block-table\"><table>\n<thead>\n<tr>\n<th>Dom\u00ednio<\/th>\n<th>Habilidades Individuais<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Financiar<\/td>\n<td>Gerenciar relat\u00f3rios de despesas, rastrear contas a receber<\/td>\n<\/tr>\n<tr>\n<td>Recursos Humanos<\/td>\n<td>Monitoramento do desempenho das colabora\u00e7\u00f5es<\/td>\n<\/tr>\n<tr>\n<td>Cadeia de mantimentos<\/td>\n<td>Otimiza\u00e7\u00e3o de pedidos de produtos<\/td>\n<\/tr>\n<tr>\n<td>Produtos<\/td>\n<td>Gest\u00e3o de manuten\u00e7\u00e3o de ativos<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/figure>\n\n<h2 class=\"wp-block-heading\">O futuro da IA \u200b\u200bcom Joule e seus agentes inteligentes<\/h2>\n\n<p class=\"wp-block-paragraph\">Al\u00e9m do assistente Joule, a SAP est\u00e1 construindo um ecossistema de<strong>agentes inteligentes<\/strong> capaz de atender \u00e0s necessidades contempor\u00e2neas das empresas. Atualmente, 14 agentes beta j\u00e1 est\u00e3o em testes, cada um oferecendo solu\u00e7\u00f5es em diversas \u00e1reas, incluindo gest\u00e3o da experi\u00eancia do cliente (CX), log\u00edstica e finan\u00e7as.<\/p>\n\n<h3 class=\"wp-block-heading\">Um portf\u00f3lio de agentes em expans\u00e3o<\/h3>\n\n<p class=\"wp-block-paragraph\">Entre o segundo e quarto trimestres de 2025, al\u00e9m dos agentes j\u00e1 dispon\u00edveis, a SAP planeja lan\u00e7ar 11 novos agentes incluindo funcionalidades como:<\/p>\n\n<ul class=\"wp-block-list\"><li>Cria\u00e7\u00e3o de propostas comerciais<\/li><li>Planejamento de manuten\u00e7\u00e3o<\/li><li>Otimiza\u00e7\u00e3o de miss\u00f5es de campo<\/li><li>Obten\u00e7\u00e3o e rastreamento de produtos<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">Com a ambi\u00e7\u00e3o de oferecer um total de 40 agentes at\u00e9 ao final de 2025, a SAP n\u00e3o deixa nada ao acaso. Os agentes Joule, semiaut\u00f4nomos e alimentados por modelos de linguagem, permitir\u00e3o uma melhor tomada de decis\u00f5es e uma intera\u00e7\u00e3o mais suave entre os departamentos.<\/p>\n\n<h3 class=\"wp-block-heading\">Desenvolvimento de um sistema de agente din\u00e2mico<\/h3>\n\n<p class=\"wp-block-paragraph\">Outro aspecto de interesse \u00e9 o lan\u00e7amento de um sistema de workflow <strong>din\u00e2mico<\/strong> planejado para o terceiro trimestre de 2025. Este sistema ter\u00e1 como objetivo permitir que os agentes executem melhor as tarefas expressas em linguagem natural, o que poder\u00e1 facilitar a ado\u00e7\u00e3o por usu\u00e1rios n\u00e3o t\u00e9cnicos.<\/p>\n\n<p class=\"wp-block-paragraph\">Neste contexto, a SAP aposta em modelos variados de linguagem e racioc\u00ednio, associados a parcerias estrat\u00e9gicas com a Mistral AI e a Google Cloud para refor\u00e7ar as suas capacidades.<\/p>\n\n<h2 class=\"wp-block-heading\">Governan\u00e7a de agentes de IA com LeanIX<\/h2>\n\n<p class=\"wp-block-paragraph\">Paralelamente ao desenvolvimento do Joule e dos agentes inteligentes, a SAP est\u00e1 introduzindo <strong>LeanIX<\/strong> como base da governan\u00e7a para gerenci\u00e1-los. Este hub de agentes pretende ser uma resposta aos desafios de automatiza\u00e7\u00e3o e efici\u00eancia, permitindo \u00e0s empresas monitorizar e otimizar a utiliza\u00e7\u00e3o dos seus diversos agentes.<\/p>\n\n<h3 class=\"wp-block-heading\">Corre\u00e7\u00e3o de preconceitos e alucina\u00e7\u00f5es<\/h3>\n\n<p class=\"wp-block-paragraph\">A governan\u00e7a do agente n\u00e3o para por a\u00ed. Em um ambiente cada vez mais automatizado, a SAP enfatiza a import\u00e2ncia \u00e9tica e regulat\u00f3ria. O centro piloto do agente inteligente fornecer\u00e1 supervis\u00e3o para abordar lacunas de automa\u00e7\u00e3o e avaliar a\u00e7\u00f5es em rela\u00e7\u00e3o aos padr\u00f5es \u00e9ticos.<\/p>\n\n<p class=\"wp-block-paragraph\">As empresas poder\u00e3o ent\u00e3o ter uma vis\u00e3o geral de como seus agentes est\u00e3o cumprindo as diretrizes, garantindo ao mesmo tempo a seguran\u00e7a e a conformidade dos processos.<\/p>\n\n<p class=\"wp-block-paragraph\">Adicionando ferramentas como <strong>pano<\/strong> e um <strong>gr\u00e1fico de conhecimento<\/strong>A SAP garante que fornece resultados de alt\u00edssima qualidade, limitando os riscos associados ao uso de modelos de intelig\u00eancia artificial.<\/p>\n\n<h3 class=\"wp-block-heading\">Acesso a dados externos e estrat\u00e9gia de parceria<\/h3>\n\n<p class=\"wp-block-paragraph\">Outra \u00e1rea-chave de inova\u00e7\u00e3o da SAP est\u00e1 no enriquecimento das respostas fornecidas pela Joule com dados externos por meio de parcerias, como a com a Perplexity. De fato, isso posiciona as empresas no centro de uma troca de informa\u00e7\u00f5es crucial para antecipar e mitigar riscos. Por exemplo, em caso de previs\u00f5es clim\u00e1ticas disruptivas, os agentes podem sugerir alternativas para reduzir os impactos na cadeia de suprimentos.<\/p>\n\n<p class=\"wp-block-paragraph\">Isso tamb\u00e9m permitir\u00e1 uma melhor integra\u00e7\u00e3o de dados internos e externos para otimizar a tomada de decis\u00f5es estrat\u00e9gicas.<\/p>\n\n<figure class=\"wp-block-table\"><table>\n<thead>\n<tr>\n<th>Nome do Agente<\/th>\n<th>\u00c1rea de aplica\u00e7\u00e3o<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Agente de gerenciamento de projetos<\/td>\n<td>Supervis\u00e3o de equipes e campanhas<\/td>\n<\/tr>\n<tr>\n<td>Agente de fornecimento<\/td>\n<td>Otimiza\u00e7\u00e3o de compras e fornecimento de produtos<\/td>\n<\/tr>\n<tr>\n<td>Agente de previs\u00e3o<\/td>\n<td>Antecipa\u00e7\u00e3o e produ\u00e7\u00e3o de tend\u00eancias<\/td>\n<\/tr>\n<tr>\n<td>Agente de suporte ao cliente<\/td>\n<td>Suporte e gerenciamento da experi\u00eancia do cliente<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/figure>\n\n<h2 class=\"wp-block-heading\">Desenvolvendo IA Ag\u00eantica: Rumo a uma Nova Era de Rob\u00f4s e Automa\u00e7\u00e3o<\/h2>\n\n<p class=\"wp-block-paragraph\">A SAP n\u00e3o pretende parar na intelig\u00eancia virtual. Em 2025, a empresa confirma sua aposta na automa\u00e7\u00e3o por meio de sistemas rob\u00f3ticos, em parceria com <strong>Neura Rob\u00f3tica<\/strong> E <strong>Nvidia<\/strong>. Essa parceria deve permitir a implanta\u00e7\u00e3o de rob\u00f4s inteligentes em ambientes variados, de f\u00e1bricas a locais de trabalho, introduzindo assim uma nova dimens\u00e3o na rela\u00e7\u00e3o entre homem e m\u00e1quina.<\/p>\n\n<h3 class=\"wp-block-heading\">Robo-agentes: o futuro da manuten\u00e7\u00e3o e automa\u00e7\u00e3o<\/h3>\n\n<p class=\"wp-block-paragraph\">Essa nova rob\u00f3tica, equipada com agentes Joule, ser\u00e1 testada para aplica\u00e7\u00f5es como manuten\u00e7\u00e3o proativa de linhas de produ\u00e7\u00e3o. Eles poderiam transformar abordagens tradicionais, tornando os processos mais eficientes e menos custosos para as empresas.<strong>SEIVA<\/strong> assim, leva a inova\u00e7\u00e3o a novos patamares, colocando-se na vanguarda de uma revolu\u00e7\u00e3o tecnol\u00f3gica.<\/p>\n\n<p class=\"wp-block-paragraph\">Neste clima de transforma\u00e7\u00e3o, a voz dos usu\u00e1rios e clientes continua sendo crucial. A SAP demonstra uma real disposi\u00e7\u00e3o de integrar constantemente o feedback para ajustar seu roteiro e atender \u00e0s necessidades do mercado.<\/p>\n\n<h3 class=\"wp-block-heading\">Uma vis\u00e3o do futuro com agentes inteligentes<\/h3>\n\n<p class=\"wp-block-paragraph\">Com um roteiro t\u00e3o abrangente e uma vis\u00e3o clara, a SAP est\u00e1 pronta n\u00e3o apenas para transformar seu pr\u00f3prio ecossistema, mas tamb\u00e9m para impactar significativamente os neg\u00f3cios ao redor do mundo. O desenvolvimento de agentes inteligentes e o suporte de ferramentas como o Joule prometem tornar a transforma\u00e7\u00e3o digital mais acess\u00edvel e eficiente.<\/p>\n\n<p class=\"wp-block-paragraph\">Ao manter uma abordagem \u00e9tica e centrada no usu\u00e1rio, a SAP aspira definir novos padr\u00f5es de intera\u00e7\u00e3o entre humanos e tecnologia. Neste contexto de constante mudan\u00e7a, o impacto destas inova\u00e7\u00f5es ter\u00e1 de ser observado de perto para avaliar o futuro da <strong>software empresarial<\/strong>.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>No alvorecer da revolu\u00e7\u00e3o digital, \u00e0 medida que a tecnologia evolui a um ritmo fren\u00e9tico, SEIVA, l\u00edder na \u00e1rea de software empresarial, est\u00e1 preparando uma grande transforma\u00e7\u00e3o em seu conjunto de ferramentas. Nos eventos Sapphire 2025, a empresa revelou suas ambi\u00e7\u00f5es em intelig\u00eancia artificial com a apresenta\u00e7\u00e3o de seu assistente Joule e seu agentes inteligentes. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34713,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[8620,62249,7064,897],"class_list":["post-34737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe-pt","tag-agentes-inteligentes-pt","tag-joule-pt","tag-seiva-pt","tag-tecnologia-pt"],"_links":{"self":[{"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/posts\/34737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/comments?post=34737"}],"version-history":[{"count":1,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/posts\/34737\/revisions"}],"predecessor-version":[{"id":34738,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/posts\/34737\/revisions\/34738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/media\/34713"}],"wp:attachment":[{"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/media?parent=34737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/categories?post=34737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mon-agent-ia.fr\/blog\/wp-json\/wp\/v2\/tags?post=34737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}